{"id":30469,"date":"2024-06-09T20:22:45","date_gmt":"2024-06-09T18:22:45","guid":{"rendered":"https:\/\/mail.replica-cycling.com\/?post_type=product&#038;p=30469"},"modified":"2026-05-13T15:36:40","modified_gmt":"2026-05-13T13:36:40","slug":"aa-drinks-leontien-nl-188","status":"publish","type":"product","link":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/tour-of-britain\/","title":{"rendered":"PASSEIO PELA GR\u00c3-BRETANHA"},"content":{"rendered":"<p>PASSEIO PELA GR\u00c3-BRETANHA<\/p>","protected":false},"excerpt":{"rendered":"<p>PASSEIO PELA GR\u00c3-BRETANHA<\/p>","protected":false},"featured_media":30479,"template":"","meta":[],"product_brand":[],"product_cat":[54],"product_tag":[],"class_list":["post-30469","product","type-product","status-publish","has-post-thumbnail","product_cat-leiderstruien","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TOUR OF BRITAIN - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/aa-drinks-leontien-nl-188\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TOUR OF BRITAIN - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"TOUR OF BRITAIN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/aa-drinks-leontien-nl-188\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:36:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1852-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/tour-of-britain\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/tour-of-britain\\\/\",\"name\":\"TOUR OF BRITAIN - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/tour-of-britain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/tour-of-britain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_1852-scaled.jpg\",\"datePublished\":\"2024-06-09T18:22:45+00:00\",\"dateModified\":\"2026-05-13T13:36:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/tour-of-britain\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/tour-of-britain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/tour-of-britain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_1852-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_1852-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"TOUR OF BRITAIN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/tour-of-britain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TOUR OF BRITAIN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TOUR DA GR\u00c3-BRETANHA - Ton Merckx Cycling Jerseys - Tour pelo mundo das camisas de ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/aa-drinks-leontien-nl-188\/","og_locale":"pt_PT","og_type":"article","og_title":"TOUR OF BRITAIN - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"TOUR OF BRITAIN","og_url":"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/aa-drinks-leontien-nl-188\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:36:40+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1852-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/tour-of-britain\/","url":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/tour-of-britain\/","name":"TOUR DA GR\u00c3-BRETANHA - Ton Merckx Cycling Jerseys - Tour pelo mundo das camisas de ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/tour-of-britain\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/tour-of-britain\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1852-scaled.jpg","datePublished":"2024-06-09T18:22:45+00:00","dateModified":"2026-05-13T13:36:40+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/tour-of-britain\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/tour-of-britain\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/tour-of-britain\/#primaryimage","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1852-scaled.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1852-scaled.jpg","width":1920,"height":2560,"caption":"TOUR OF BRITAIN"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/tour-of-britain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"TOUR OF BRITAIN"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","description":"milhares de camisas de ciclismo originais - encomende a sua r\u00e9plica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/product\/30469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/media\/30479"}],"wp:attachment":[{"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/media?parent=30469"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/product_brand?post=30469"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/product_cat?post=30469"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/product_tag?post=30469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}