{"id":30168,"date":"2024-06-07T22:32:51","date_gmt":"2024-06-07T20:32:51","guid":{"rendered":"https:\/\/mail.replica-cycling.com\/?post_type=product&#038;p=30168"},"modified":"2026-05-13T15:36:42","modified_gmt":"2026-05-13T13:36:42","slug":"general-ranking-42","status":"publish","type":"product","link":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/comunitat-valenciana-com-2005\/","title":{"rendered":"CAMISA COMUNITAT VALENCIANA (a)-ORBEA 2005"},"content":{"rendered":"<p>COMUNIDADE VALENCIANA.COM 2005<\/p>","protected":false},"excerpt":{"rendered":"<p>COMUNIDADE VALENCIANA.COM 2005<\/p>","protected":false},"featured_media":30178,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-30168","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMUNITAT VALENCIANA (a)-ORBEA 2005  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMUNITAT VALENCIANA (a)-ORBEA 2005  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"COMUNITAT VALENCIANA.COM 2005\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:36:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1865-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/camisa-de-ciclismo-retro\\\/general-ranking-42\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/camisa-de-ciclismo-retro\\\/general-ranking-42\\\/\",\"name\":\"COMUNITAT VALENCIANA (a)-ORBEA 2005 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/camisa-de-ciclismo-retro\\\/general-ranking-42\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/camisa-de-ciclismo-retro\\\/general-ranking-42\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_1865-scaled.jpg\",\"datePublished\":\"2024-06-07T20:32:51+00:00\",\"dateModified\":\"2026-05-13T13:36:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/camisa-de-ciclismo-retro\\\/general-ranking-42\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/camisa-de-ciclismo-retro\\\/general-ranking-42\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/camisa-de-ciclismo-retro\\\/general-ranking-42\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_1865-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_1865-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"COMUNITAT VALENCIANA.COM 2005\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/camisa-de-ciclismo-retro\\\/general-ranking-42\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COMUNITAT VALENCIANA (a)-ORBEA 2005 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAMISA DE CICLISMO COMUNITAT VALENCIANA (a)-ORBEA 2005 - Camisas de Ciclismo Ton Merckx - Uma viagem pelo mundo das camisas de ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/","og_locale":"pt_PT","og_type":"article","og_title":"COMUNITAT VALENCIANA (a)-ORBEA 2005  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"COMUNITAT VALENCIANA.COM 2005","og_url":"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:36:42+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1865-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/","url":"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/","name":"CAMISA DE CICLISMO COMUNITAT VALENCIANA (a)-ORBEA 2005 - Camisas de Ciclismo Ton Merckx - Uma viagem pelo mundo das camisas de ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1865-scaled.jpg","datePublished":"2024-06-07T20:32:51+00:00","dateModified":"2026-05-13T13:36:42+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/#primaryimage","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1865-scaled.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2024\/06\/IMG_1865-scaled.jpg","width":1920,"height":2560,"caption":"COMUNITAT VALENCIANA.COM 2005"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/pt\/camisa-de-ciclismo-retro\/general-ranking-42\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"COMUNITAT VALENCIANA (a)-ORBEA 2005 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","description":"milhares de camisas de ciclismo originais - encomende a sua r\u00e9plica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/product\/30168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/media\/30178"}],"wp:attachment":[{"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/media?parent=30168"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/product_brand?post=30168"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/product_cat?post=30168"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/pt\/wp-json\/wp\/v2\/product_tag?post=30168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}