{"id":667,"date":"2023-01-24T17:29:28","date_gmt":"2023-01-24T17:29:28","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/algemeen-klassement-19\/"},"modified":"2026-06-22T09:01:52","modified_gmt":"2026-06-22T07:01:52","slug":"classificazione-generale-19","status":"publish","type":"product","link":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/algemeen-klassement-19\/","title":{"rendered":"EVENTO DI PI\u00d9 GIORNI DI CICLISMO NOORDENVELD\/WESTERKWARTIER (a)- CLASSIFICA GENERALE \u2013 ???? \u2013 MAGLIA DA CICLISMO"},"content":{"rendered":"<p>NOORDENVELD\/WESTERKWARTIER CICLISMO CICLISMO DI PI\u00d9 GIORNI \u2013 CLASSIFICA GENERALE<\/p>\n<p>Maglietta indossata da Tonnie Teuben<\/p>","protected":false},"excerpt":{"rendered":"<p>EVENTO CICLISMO DI PI\u00d9 GIORNI NOORDENVELD\/WESTERKWARTIER \u2013 CLASSIFICA GENERALE Maglia indossata da Tonnie Teuben<\/p>","protected":false},"featured_media":189142,"template":"","meta":[],"product_brand":[],"product_cat":[54],"product_tag":[],"class_list":["post-667","product","type-product","status-publish","has-post-thumbnail","product_cat-leiderstruien","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WIELERMEERDAAGSE NOORDENVELD\/WESTERKWARTIER (a)- ALGEMEEN KLASSEMENT - ???? - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-19\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WIELERMEERDAAGSE NOORDENVELD\/WESTERKWARTIER (a)- ALGEMEEN KLASSEMENT - ???? - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"WIELERMEERDAAGSE NOORDENVELD\/WESTERKWARTIER &#8211; ALGEMEEN KLASSEMENT Shirt gedragen door Tonnie Teuben\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T07:01:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/003-29-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/algemeen-klassement-19\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/algemeen-klassement-19\\\/\",\"name\":\"WIELERMEERDAAGSE NOORDENVELD\\\/WESTERKWARTIER (a)- ALGEMEEN KLASSEMENT - ???? - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/algemeen-klassement-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/algemeen-klassement-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/003-29-scaled.jpg\",\"datePublished\":\"2023-01-24T17:29:28+00:00\",\"dateModified\":\"2026-06-22T07:01:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/algemeen-klassement-19\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/algemeen-klassement-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/algemeen-klassement-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/003-29-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/003-29-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"WIELERMEERDAAGSE NOORDENVELD\\\/WESTERKWARTIER - ALGEMEEN KLASSEMENT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/algemeen-klassement-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WIELERMEERDAAGSE NOORDENVELD\\\/WESTERKWARTIER (a)- ALGEMEEN KLASSEMENT &#8211; ???? &#8211; WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GARA CICLISTICA DI PI\u00d9 GIORNI NOORDENVELD\/WESTERKWARTIER (a) - CLASSIFICA GENERALE - ???? - MAGLIA DA CICLISMO - Maglie da ciclismo Ton Merckx - Un viaggio nel mondo delle maglie da ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-19\/","og_locale":"it_IT","og_type":"article","og_title":"WIELERMEERDAAGSE NOORDENVELD\/WESTERKWARTIER (a)- ALGEMEEN KLASSEMENT - ???? - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"WIELERMEERDAAGSE NOORDENVELD\/WESTERKWARTIER &#8211; ALGEMEEN KLASSEMENT Shirt gedragen door Tonnie Teuben","og_url":"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/classificazione-generale-19\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-06-22T07:01:52+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/003-29-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/algemeen-klassement-19\/","url":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/algemeen-klassement-19\/","name":"GARA CICLISTICA DI PI\u00d9 GIORNI NOORDENVELD\/WESTERKWARTIER (a) - CLASSIFICA GENERALE - ???? - MAGLIA DA CICLISMO - Maglie da ciclismo Ton Merckx - Un viaggio nel mondo delle maglie da ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/algemeen-klassement-19\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/algemeen-klassement-19\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/003-29-scaled.jpg","datePublished":"2023-01-24T17:29:28+00:00","dateModified":"2026-06-22T07:01:52+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/algemeen-klassement-19\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/algemeen-klassement-19\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/algemeen-klassement-19\/#primaryimage","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/003-29-scaled.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/003-29-scaled.jpg","width":1920,"height":2560,"caption":"WIELERMEERDAAGSE NOORDENVELD\/WESTERKWARTIER - ALGEMEEN KLASSEMENT"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/algemeen-klassement-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"WIELERMEERDAAGSE NOORDENVELD\/WESTERKWARTIER (a)- ALGEMEEN KLASSEMENT &#8211; ???? &#8211; WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.replica-cycling.com\/it\/wp-json\/wp\/v2\/product\/667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.replica-cycling.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.replica-cycling.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/it\/wp-json\/wp\/v2\/media\/189142"}],"wp:attachment":[{"href":"https:\/\/mail.replica-cycling.com\/it\/wp-json\/wp\/v2\/media?parent=667"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/it\/wp-json\/wp\/v2\/product_brand?post=667"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/it\/wp-json\/wp\/v2\/product_cat?post=667"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/it\/wp-json\/wp\/v2\/product_tag?post=667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}