{"id":641,"date":"2023-01-24T17:29:19","date_gmt":"2023-01-24T17:29:19","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/algemeen-klassement-13\/"},"modified":"2026-05-13T15:40:11","modified_gmt":"2026-05-13T13:40:11","slug":"clasificacion-general-13","status":"publish","type":"product","link":"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/algemeen-klassement-13\/","title":{"rendered":"THURINGEN RUNDFARTH \u2013 CLASIFICACI\u00d3N GENERAL"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":326,"template":"","meta":[],"product_brand":[],"product_cat":[54],"product_tag":[],"class_list":["post-641","product","type-product","status-publish","has-post-thumbnail","product_cat-leiderstruien","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>THURINGEN RUNDFARTH - ALGEMEEN KLASSEMENT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"THURINGEN RUNDFARTH - ALGEMEEN KLASSEMENT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:40:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA45257-rotated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-wielershirt\\\/algemeen-klassement-13\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-wielershirt\\\/algemeen-klassement-13\\\/\",\"name\":\"THURINGEN RUNDFARTH - ALGEMEEN KLASSEMENT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-wielershirt\\\/algemeen-klassement-13\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-wielershirt\\\/algemeen-klassement-13\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA45257-rotated.jpg\",\"datePublished\":\"2023-01-24T17:29:19+00:00\",\"dateModified\":\"2026-05-13T13:40:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-wielershirt\\\/algemeen-klassement-13\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-wielershirt\\\/algemeen-klassement-13\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-wielershirt\\\/algemeen-klassement-13\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA45257-rotated.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA45257-rotated.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/en\\\/retro-wielershirt\\\/algemeen-klassement-13\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"THURINGEN RUNDFARTH &#8211; ALGEMEEN KLASSEMENT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"THURINGEN RUNDFARTH - CLASIFICACI\u00d3N GENERAL - Maillots de ciclismo Ton Merckx - Tour por el mundo de los maillots de ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/","og_locale":"es_ES","og_type":"article","og_title":"THURINGEN RUNDFARTH - ALGEMEEN KLASSEMENT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:40:11+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA45257-rotated.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/","url":"https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/","name":"THURINGEN RUNDFARTH - CLASIFICACI\u00d3N GENERAL - Maillots de ciclismo Ton Merckx - Tour por el mundo de los maillots de ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/#primaryimage"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/SSA45257-rotated.jpg","datePublished":"2023-01-24T17:29:19+00:00","dateModified":"2026-05-13T13:40:11+00:00","breadcrumb":{"@id":"https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/#primaryimage","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/SSA45257-rotated.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/SSA45257-rotated.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cycling-originals.com\/en\/retro-wielershirt\/algemeen-klassement-13\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"THURINGEN RUNDFARTH &#8211; ALGEMEEN KLASSEMENT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Camisetas ciclistas Ton Merckx - Recorrido por el mundo de las camisetas ciclistas","description":"miles de maillots ciclistas originales - \u00a1pide tu r\u00e9plica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Camisetas ciclistas Ton Merckx - Recorrido por el mundo de las camisetas ciclistas","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/product\/641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/media\/326"}],"wp:attachment":[{"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/media?parent=641"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/product_brand?post=641"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/product_cat?post=641"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/product_tag?post=641"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}