{"id":1952,"date":"2023-01-24T17:43:54","date_gmt":"2023-01-24T17:43:54","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/ville-de-charleroi\/"},"modified":"2026-05-13T15:39:13","modified_gmt":"2026-05-13T13:39:13","slug":"ciudad-de-charleroi","status":"publish","type":"product","link":"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/ville-de-charleroi\/","title":{"rendered":"VILLE DE CHARLEROI (a)-CAMISETA DE CICLISMO NEW SYSTEMS 2000"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":177375,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-1952","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VILLE DE CHARLEROI (a)-NEW SYSTEMS  2000  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/es\/maillot-ciclista-retro\/ciudad-de-charleroi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VILLE DE CHARLEROI (a)-NEW SYSTEMS  2000  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/es\/maillot-ciclista-retro\/ciudad-de-charleroi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:39:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_4469-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/ville-de-charleroi\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/ville-de-charleroi\\\/\",\"name\":\"VILLE DE CHARLEROI (a)-NEW SYSTEMS 2000 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/ville-de-charleroi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/ville-de-charleroi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4469-scaled.jpg\",\"datePublished\":\"2023-01-24T17:43:54+00:00\",\"dateModified\":\"2026-05-13T13:39:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/ville-de-charleroi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/ville-de-charleroi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/ville-de-charleroi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4469-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4469-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/ville-de-charleroi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"VILLE DE CHARLEROI (a)-NEW SYSTEMS 2000 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VILLE DE CHARLEROI (a)-CAMISETA DE CICLISMO NEW SYSTEMS 2000 - Maillots de ciclismo Ton Merckx - Recorrido por el mundo de los maillots de ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/es\/maillot-ciclista-retro\/ciudad-de-charleroi\/","og_locale":"es_ES","og_type":"article","og_title":"VILLE DE CHARLEROI (a)-NEW SYSTEMS  2000  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.replica-cycling.com\/es\/maillot-ciclista-retro\/ciudad-de-charleroi\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:39:13+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_4469-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/ville-de-charleroi\/","url":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/ville-de-charleroi\/","name":"VILLE DE CHARLEROI (a)-CAMISETA DE CICLISMO NEW SYSTEMS 2000 - Maillots de ciclismo Ton Merckx - Tour por el mundo de los maillots de ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/ville-de-charleroi\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/ville-de-charleroi\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_4469-scaled.jpg","datePublished":"2023-01-24T17:43:54+00:00","dateModified":"2026-05-13T13:39:13+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/ville-de-charleroi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/ville-de-charleroi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/ville-de-charleroi\/#primaryimage","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_4469-scaled.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_4469-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/ville-de-charleroi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"VILLE DE CHARLEROI (a)-NEW SYSTEMS 2000 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Camisetas ciclistas Ton Merckx - Recorrido por el mundo de las camisetas ciclistas","description":"miles de maillots ciclistas originales - \u00a1pide tu r\u00e9plica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Camisetas ciclistas Ton Merckx - Recorrido por el mundo de las camisetas ciclistas","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/product\/1952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/media\/177375"}],"wp:attachment":[{"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/media?parent=1952"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/product_brand?post=1952"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/product_cat?post=1952"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/es\/wp-json\/wp\/v2\/product_tag?post=1952"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}