{"id":178977,"date":"2026-05-09T16:18:28","date_gmt":"2026-05-09T14:18:28","guid":{"rendered":"https:\/\/www.tonmerckxwielershirts.nl\/?post_type=product&#038;p=178977"},"modified":"2026-05-13T15:36:20","modified_gmt":"2026-05-13T13:36:20","slug":"quickstep-qa-soudal-2025-radtrikot","status":"publish","type":"product","link":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/quickstep-qa-soudal-2025-wielershirt\/","title":{"rendered":"QUICKSTEP (qa)-SOUDAL 2025 RADSHIRT"},"content":{"rendered":"<p>QUICKSTEP-SOUTAL 2025<\/p>","protected":false},"excerpt":{"rendered":"<p>QUICKSTEP-SOUTAL 2025<\/p>","protected":false},"featured_media":178978,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-178977","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QUICKSTEP (qa)-SOUDAL  2025   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QUICKSTEP (qa)-SOUDAL  2025   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"QUICKSTEP-SOUDAL 2025\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:36:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vintagecycling.store\/wp-content\/uploads\/2026\/05\/IMG_20260509_155809-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/maillot-cyclisme-quickstep-qa-soudal-2025\\\/\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/maillot-cyclisme-quickstep-qa-soudal-2025\\\/\",\"name\":\"QUICKSTEP (qa)-SOUDAL 2025 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/maillot-cyclisme-quickstep-qa-soudal-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/maillot-cyclisme-quickstep-qa-soudal-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_20260509_155809-scaled.jpg\",\"datePublished\":\"2026-05-09T14:18:28+00:00\",\"dateModified\":\"2026-05-13T13:36:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/maillot-cyclisme-quickstep-qa-soudal-2025\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/maillot-cyclisme-quickstep-qa-soudal-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/maillot-cyclisme-quickstep-qa-soudal-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_20260509_155809-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_20260509_155809-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"QUICKSTEP-SOUDAL 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/maillot-cyclisme-quickstep-qa-soudal-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"QUICKSTEP (qa)-SOUDAL 2025 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.replica-cycling.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QUICKSTEP (qa)-SOUDAL 2025 Radtrikot - Ton Merckx Radtrikots - Eine Reise durch die Welt der Radtrikots","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/","og_locale":"de_DE","og_type":"article","og_title":"QUICKSTEP (qa)-SOUDAL  2025   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"QUICKSTEP-SOUDAL 2025","og_url":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:36:20+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2026\/05\/IMG_20260509_155809-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/","url":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/","name":"QUICKSTEP (qa)-SOUDAL 2025 Radtrikot - Ton Merckx Radtrikots - Eine Reise durch die Welt der Radtrikots","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/#primaryimage"},"image":{"@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2026\/05\/IMG_20260509_155809-scaled.jpg","datePublished":"2026-05-09T14:18:28+00:00","dateModified":"2026-05-13T13:36:20+00:00","breadcrumb":{"@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/#primaryimage","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2026\/05\/IMG_20260509_155809-scaled.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2026\/05\/IMG_20260509_155809-scaled.jpg","width":1920,"height":2560,"caption":"QUICKSTEP-SOUDAL 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/maillot-cyclisme-quickstep-qa-soudal-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"QUICKSTEP (qa)-SOUDAL 2025 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","description":"Tausende originale Radtrikots \u2013 bestellen Sie Ihr Replikat!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.replica-cycling.com\/de\/wp-json\/wp\/v2\/product\/178977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.replica-cycling.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.replica-cycling.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/de\/wp-json\/wp\/v2\/media\/178978"}],"wp:attachment":[{"href":"https:\/\/mail.replica-cycling.com\/de\/wp-json\/wp\/v2\/media?parent=178977"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/de\/wp-json\/wp\/v2\/product_brand?post=178977"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/de\/wp-json\/wp\/v2\/product_cat?post=178977"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.replica-cycling.com\/de\/wp-json\/wp\/v2\/product_tag?post=178977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}